{"id":2251,"date":"2024-01-09T15:44:33","date_gmt":"2024-01-09T20:44:33","guid":{"rendered":"https:\/\/vende24.com.co\/tiendas\/?post_type=product&#038;p=2251"},"modified":"2024-01-09T15:44:33","modified_gmt":"2024-01-09T20:44:33","slug":"maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9","status":"publish","type":"product","link":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/","title":{"rendered":"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9"},"content":{"rendered":"<ul style=\"font-family: rocketfont;font-size: 15.04px\">\n<li><span style=\"font-weight: bolder\">Tama\u00f1o Aprox. producto:<\/span>\u00a015 x 4 x 4 cm.<\/li>\n<li><span style=\"font-weight: bolder\">Peso:<\/span>\u00a0135 g.<\/li>\n<li><span style=\"font-weight: bolder\">Funcionamiento:<\/span>\u00a0Bater\u00eda recargable extra\u00edble 18650.<\/li>\n<li><span style=\"font-weight: bolder\">Fuente de alimentaci\u00f3n:<\/span>\u00a05V<\/li>\n<li><span style=\"font-weight: bolder\">Tipo de bater\u00eda:<\/span>\u00a0Litio 18650 (interna no extra\u00edble).<\/li>\n<li><span style=\"font-weight: bolder\">Potencia:<\/span>\u00a05 W.<\/li>\n<li><span style=\"font-weight: bolder\">Tiempo de carga:<\/span>\u00a02 horas.<\/li>\n<li><span style=\"font-weight: bolder\">Tiempo de funcionamiento:<\/span>\u00a02 horas.<\/li>\n<li><span style=\"font-weight: bolder\">Gu\u00edas (peines):<\/span>\u00a01,5 mm, 2 mm, 3 mm y 4 mm.<\/li>\n<li>Crea cortes \u00fanicos con est\u00e1 potente m\u00e1quina, podr\u00e1s crear todo tipo de desvanecidos en el cabello del cliente, como tambi\u00e9n hacer l\u00edneas perfectas.<\/li>\n<li>Una m\u00e1quina de gran capacidad que puedes usar inal\u00e1mbricamente hasta 2 horas consecutivas.<\/li>\n<li>La patillera tiene un hermoso dise\u00f1o de drag\u00f3n en el mango. Adem\u00e1s, el dise\u00f1o tiene relieve lo cual lo hace lucir impresionantemente \u00fanico.<\/li>\n<li>La m\u00e1quina est\u00e1 especialmente dise\u00f1ada para no lastimar la piel de quien la use pudiendo hacer la suficiente presi\u00f3n para cortar hasta el cabello m\u00e1s peque\u00f1o.<\/li>\n<li>Perfecto para barber\u00edas, para trabajo constante moderado profesional.<\/li>\n<li>Patillera s\u00faper silenciosa que corta f\u00e1cilmente todo tipo de cabello.<\/li>\n<li>La m\u00e1quina cuenta con tres gu\u00edas, aceite para lubricar y escoba de limpieza.<\/li>\n<li>Puedes usarla tanto en adultos como ni\u00f1os.<\/li>\n<li><span style=\"font-weight: bolder\">Contenido del paquete:<\/span><\/li>\n<li>1 Patillera profesional recargable.<\/li>\n<li>4 Gu\u00edas (peines).<\/li>\n<li>1 Aceite para lubricar.<\/li>\n<li>1 Escoba de limpieza.<\/li>\n<li>1 Cargador USB.<\/li>\n<li><span style=\"font-weight: bolder\">100 % Nuevos.<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<ul style=\"font-family: rocketfont;font-size: 15.04px\">\n<li><span style=\"font-weight: bolder\">Tama\u00f1o Aprox. producto:<\/span>\u00a015 x 4 x 4 cm.<\/li>\n<li><span style=\"font-weight: bolder\">Peso:<\/span>\u00a0135 g.<\/li>\n<li><span style=\"font-weight: bolder\">Funcionamiento:<\/span>\u00a0Bater\u00eda recargable extra\u00edble 18650.<\/li>\n<li><span style=\"font-weight: bolder\">Fuente de alimentaci\u00f3n:<\/span>\u00a05V<\/li>\n<li><span style=\"font-weight: bolder\">Tipo de bater\u00eda:<\/span>\u00a0Litio 18650 (interna no extra\u00edble).<\/li>\n<li><span style=\"font-weight: bolder\">Potencia:<\/span>\u00a05 W.<\/li>\n<li><span style=\"font-weight: bolder\">Tiempo de carga:<\/span>\u00a02 horas.<\/li>\n<li><span style=\"font-weight: bolder\">Tiempo de funcionamiento:<\/span>\u00a02 horas.<\/li>\n<li><span style=\"font-weight: bolder\">Gu\u00edas (peines):<\/span>\u00a01,5 mm, 2 mm, 3 mm y 4 mm.<\/li>\n<li>Crea cortes \u00fanicos con est\u00e1 potente m\u00e1quina, podr\u00e1s crear todo tipo de desvanecidos en el cabello del cliente, como tambi\u00e9n hacer l\u00edneas perfectas.<\/li>\n<li>Una m\u00e1quina de gran capacidad que puedes usar inal\u00e1mbricamente hasta 2 horas consecutivas.<\/li>\n<li>La patillera tiene un hermoso dise\u00f1o de drag\u00f3n en el mango. Adem\u00e1s, el dise\u00f1o tiene relieve lo cual lo hace lucir impresionantemente \u00fanico.<\/li>\n<li>La m\u00e1quina est\u00e1 especialmente dise\u00f1ada para no lastimar la piel de quien la use pudiendo hacer la suficiente presi\u00f3n para cortar hasta el cabello m\u00e1s peque\u00f1o.<\/li>\n<li>Perfecto para barber\u00edas, para trabajo constante moderado profesional.<\/li>\n<li>Patillera s\u00faper silenciosa que corta f\u00e1cilmente todo tipo de cabello.<\/li>\n<li>La m\u00e1quina cuenta con tres gu\u00edas, aceite para lubricar y escoba de limpieza.<\/li>\n<li>Puedes usarla tanto en adultos como ni\u00f1os.<\/li>\n<\/ul>\n","protected":false},"featured_media":2250,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[47,50],"product_tag":[272,274,275,277,270,271,273,276],"class_list":["post-2251","product","type-product","status-publish","has-post-thumbnail","product_cat-hogar-y-electrodomesticos","product_cat-salud-y-belleza","product_tag-cortadora-de-pelo","product_tag-cortadora-de-pelo-recargable","product_tag-maquina","product_tag-maquina-de-corta-pelo-inhalambrica","product_tag-maquina-motilar","product_tag-maquina-motilar-patillera","product_tag-maquina-motilar-recargable","product_tag-motilar-inhalabrica","entry","has-media","first","instock","shipping-taxable","purchasable","product-type-simple","has-product-nav","col","span_1_of_4","owp-content-left","owp-thumbs-layout-horizontal","owp-btn-very-big","owp-tabs-layout-horizontal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9 - Vende24.com Marketplace Colombia<\/title>\n<meta name=\"description\" content=\"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9, Crea cortes \u00fanicos con est\u00e1 potente m\u00e1quina, podr\u00e1s crear todo tipo de desvanecidos en el cabello del cliente, como tambi\u00e9n hacer l\u00edneas perfectas. Una m\u00e1quina de gran capacidad que puedes usar inal\u00e1mbricamente hasta 2 horas consecutivas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9 - Vende24.com Marketplace Colombia\" \/>\n<meta property=\"og:description\" content=\"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9, Crea cortes \u00fanicos con est\u00e1 potente m\u00e1quina, podr\u00e1s crear todo tipo de desvanecidos en el cabello del cliente, como tambi\u00e9n hacer l\u00edneas perfectas. Una m\u00e1quina de gran capacidad que puedes usar inal\u00e1mbricamente hasta 2 horas consecutivas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/\" \/>\n<meta property=\"og:site_name\" content=\"Vende24.com Marketplace Colombia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vende24.com.co\/tiendas\/wp-content\/uploads\/2024\/01\/MAQUINA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/marketplace\\\/hogar-y-electrodomesticos\\\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\\\/\",\"url\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/marketplace\\\/hogar-y-electrodomesticos\\\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\\\/\",\"name\":\"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9 - Vende24.com Marketplace Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/marketplace\\\/hogar-y-electrodomesticos\\\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/marketplace\\\/hogar-y-electrodomesticos\\\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/MAQUINA.png\",\"datePublished\":\"2024-01-09T20:44:33+00:00\",\"description\":\"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9, Crea cortes \u00fanicos con est\u00e1 potente m\u00e1quina, podr\u00e1s crear todo tipo de desvanecidos en el cabello del cliente, como tambi\u00e9n hacer l\u00edneas perfectas. Una m\u00e1quina de gran capacidad que puedes usar inal\u00e1mbricamente hasta 2 horas consecutivas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/marketplace\\\/hogar-y-electrodomesticos\\\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/marketplace\\\/hogar-y-electrodomesticos\\\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/marketplace\\\/hogar-y-electrodomesticos\\\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/MAQUINA.png\",\"contentUrl\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/MAQUINA.png\",\"width\":660,\"height\":654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/marketplace\\\/hogar-y-electrodomesticos\\\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"marketplace\",\"item\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/marketplace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/#website\",\"url\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/\",\"name\":\"Vende24.com.co el Marketplace de Colombia\",\"description\":\"Promociones, ofertas y descuentos de las mejores tiendas de Colombia\",\"publisher\":{\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/#organization\"},\"alternateName\":\"El Marketplace de Colombia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/#organization\",\"name\":\"Vende24 el Marketplace de Colombia\",\"alternateName\":\"El Marketplace de Colombia\",\"url\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/V24rojo_091720.png\",\"contentUrl\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/V24rojo_091720.png\",\"width\":460,\"height\":80,\"caption\":\"Vende24 el Marketplace de Colombia\"},\"image\":{\"@id\":\"https:\\\/\\\/vende24.com.co\\\/tiendas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9 - Vende24.com Marketplace Colombia","description":"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9, Crea cortes \u00fanicos con est\u00e1 potente m\u00e1quina, podr\u00e1s crear todo tipo de desvanecidos en el cabello del cliente, como tambi\u00e9n hacer l\u00edneas perfectas. Una m\u00e1quina de gran capacidad que puedes usar inal\u00e1mbricamente hasta 2 horas consecutivas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9 - Vende24.com Marketplace Colombia","og_description":"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9, Crea cortes \u00fanicos con est\u00e1 potente m\u00e1quina, podr\u00e1s crear todo tipo de desvanecidos en el cabello del cliente, como tambi\u00e9n hacer l\u00edneas perfectas. Una m\u00e1quina de gran capacidad que puedes usar inal\u00e1mbricamente hasta 2 horas consecutivas.","og_url":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/","og_site_name":"Vende24.com Marketplace Colombia","og_image":[{"width":660,"height":654,"url":"https:\/\/vende24.com.co\/tiendas\/wp-content\/uploads\/2024\/01\/MAQUINA.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/","url":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/","name":"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9 - Vende24.com Marketplace Colombia","isPartOf":{"@id":"https:\/\/vende24.com.co\/tiendas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/#primaryimage"},"image":{"@id":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/#primaryimage"},"thumbnailUrl":"https:\/\/vende24.com.co\/tiendas\/wp-content\/uploads\/2024\/01\/MAQUINA.png","datePublished":"2024-01-09T20:44:33+00:00","description":"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9, Crea cortes \u00fanicos con est\u00e1 potente m\u00e1quina, podr\u00e1s crear todo tipo de desvanecidos en el cabello del cliente, como tambi\u00e9n hacer l\u00edneas perfectas. Una m\u00e1quina de gran capacidad que puedes usar inal\u00e1mbricamente hasta 2 horas consecutivas.","breadcrumb":{"@id":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/#primaryimage","url":"https:\/\/vende24.com.co\/tiendas\/wp-content\/uploads\/2024\/01\/MAQUINA.png","contentUrl":"https:\/\/vende24.com.co\/tiendas\/wp-content\/uploads\/2024\/01\/MAQUINA.png","width":660,"height":654},{"@type":"BreadcrumbList","@id":"https:\/\/vende24.com.co\/tiendas\/marketplace\/hogar-y-electrodomesticos\/maquina-motilar-patillera-buda-dorada-cortadora-pelo-t9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vende24.com.co\/tiendas\/"},{"@type":"ListItem","position":2,"name":"marketplace","item":"https:\/\/vende24.com.co\/tiendas\/marketplace\/"},{"@type":"ListItem","position":3,"name":"M\u00e1quina Motilar Patillera Buda Dorada Cortadora Pelo T9"}]},{"@type":"WebSite","@id":"https:\/\/vende24.com.co\/tiendas\/#website","url":"https:\/\/vende24.com.co\/tiendas\/","name":"Vende24.com.co el Marketplace de Colombia","description":"Promociones, ofertas y descuentos de las mejores tiendas de Colombia","publisher":{"@id":"https:\/\/vende24.com.co\/tiendas\/#organization"},"alternateName":"El Marketplace de Colombia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vende24.com.co\/tiendas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vende24.com.co\/tiendas\/#organization","name":"Vende24 el Marketplace de Colombia","alternateName":"El Marketplace de Colombia","url":"https:\/\/vende24.com.co\/tiendas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vende24.com.co\/tiendas\/#\/schema\/logo\/image\/","url":"https:\/\/vende24.com.co\/tiendas\/wp-content\/uploads\/2020\/04\/V24rojo_091720.png","contentUrl":"https:\/\/vende24.com.co\/tiendas\/wp-content\/uploads\/2020\/04\/V24rojo_091720.png","width":460,"height":80,"caption":"Vende24 el Marketplace de Colombia"},"image":{"@id":"https:\/\/vende24.com.co\/tiendas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/product\/2251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/comments?post=2251"}],"version-history":[{"count":0,"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/product\/2251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/media\/2250"}],"wp:attachment":[{"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/media?parent=2251"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/product_brand?post=2251"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/product_cat?post=2251"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vende24.com.co\/tiendas\/wp-json\/wp\/v2\/product_tag?post=2251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}